{"id":1152,"date":"2018-11-30T11:41:46","date_gmt":"2018-11-30T10:41:46","guid":{"rendered":"http:\/\/www.milltech.it\/?p=1152"},"modified":"2018-11-30T11:41:46","modified_gmt":"2018-11-30T10:41:46","slug":"betriebsferien-07-12-weihnachtsferien","status":"publish","type":"post","link":"https:\/\/www.milltech.it\/de\/2018\/11\/betriebsferien-07-12-weihnachtsferien\/","title":{"rendered":"Betriebsferien 07.12 + Weihnachtsferien"},"content":{"rendered":"<p>Milltech wird am 07.12.18 f\u00fcr lokalen Festtag geschlossen sein.<\/p>\n<p>Au\u00dferdem wird die Firma vom 22.12.18 zum 01.01.19 f\u00fcr Betriebsferien geschlossen sein werden.<\/p>\n<p>Wir bedanken uns f\u00fcr Ihr Verst\u00e4ndnis und nutzen gerne die Gelegenheit, um schon sch\u00f6ne Weihnachtstagen zu w\u00fcnschen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milltech wird am 07.12.18 f\u00fcr lokalen Festtag geschlossen sein. Au\u00dferdem wird die Firma vom 22.12.18 zum 01.01.19 f\u00fcr Betriebsferien geschlossen sein werden. Wir bedanken uns f\u00fcr Ihr Verst\u00e4ndnis und nutzen gerne die Gelegenheit, um schon sch\u00f6ne Weihnachtstagen zu w\u00fcnschen.<\/p>\n","protected":false},"author":4,"featured_media":1140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[53,47,52],"class_list":{"0":"post-1152","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-unternehmen","8":"tag-betriebsferien","9":"tag-milltech","10":"tag-weihnachten-2018","12":"post-with-thumbnail","13":"post-with-thumbnail-large"},"_links":{"self":[{"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":1,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":1153,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/posts\/1152\/revisions\/1153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/media\/1140"}],"wp:attachment":[{"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.milltech.it\/de\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}